{"id":23373,"date":"2021-01-13T09:29:45","date_gmt":"2021-01-13T08:29:45","guid":{"rendered":"https:\/\/standuppaddleboardworld.com\/?page_id=23373"},"modified":"2022-02-24T11:59:19","modified_gmt":"2022-02-24T10:59:19","slug":"moai-106","status":"publish","type":"page","link":"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/","title":{"rendered":"\u00c9valuation du paddle MOAI 10&rsquo;6&Prime;"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Le_paddle_le_plus_stable_pour_debuter_et_un_magnifique_design\"><\/span>Le paddle le plus stable pour d\u00e9buter et un magnifique design<span class=\"ez-toc-section-end\"><\/span><\/h2><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-flat ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a03e6f62eebf\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #1a2b49;color:#1a2b49\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #1a2b49;color:#1a2b49\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a03e6f62eebf\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Le_paddle_le_plus_stable_pour_debuter_et_un_magnifique_design\" >Le paddle le plus stable pour d\u00e9buter et un magnifique design<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Le_MOAI_106%E2%80%B3_convient_surtout_pour\" >Le MOAI 10&rsquo;6&Prime; convient surtout pour :<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Mon_experience\" >Mon exp\u00e9rience<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Principales_caracteristiques\" >Principales caract\u00e9ristiques<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Inclus_dans_le_package\" >Inclus dans le package<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Accessoires_optionnels_non_inclus\" >Accessoires optionnels (non inclus)<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Differences_entre_un_paddle_gonflable_et_un_paddle_rigide\" >Diff\u00e9rences entre un paddle gonflable et un paddle rigide<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Autres_revues_en_ligne_sur_le_MOAI_106%E2%80%B3\" >Autres revues en ligne sur le MOAI 10&rsquo;6&Prime;<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Questions_frequentes_a_propos_du_MOAI_106%E2%80%B3\" >Questions fr\u00e9quentes \u00e0 propos du MOAI 10&rsquo;6&Prime;<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Combien_mesure_le_MOAI_106%E2%80%B3\" >Combien mesure le MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Quelle_est_la_capacite_de_charge_maximale_du_MOAI_106%E2%80%B3\" >Quelle est la capacit\u00e9 de charge maximale du MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Quest-ce_qui_est_inclus_avec_le_MOAI_106%E2%80%B3\" >Qu&rsquo;est-ce qui est inclus avec le MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Combien_pese_le_MOAI_106%E2%80%B3\" >Combien p\u00e8se le MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#De_combien_dailerons_est_equipe_le_MOAI_106%E2%80%B3\" >De combien d&rsquo;ailerons est \u00e9quip\u00e9 le MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#De_combien_danneaux_en_D_est_equipe_le_MOAI_106%E2%80%B3\" >De combien d&rsquo;anneaux en D est \u00e9quipe le MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Quelle_est_la_duree_de_garantie_du_MOAI_106%E2%80%B3\" >Quelle est la dur\u00e9e de garantie du MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Le_MOAI_106%E2%80%B3_est-il_equipe_dun_support_de_GoPro\" >Le MOAI 10&rsquo;6&Prime; est-il \u00e9quip\u00e9 d&rsquo;un support de GoPro ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#De_combien_de_poignees_est_equipe_le_MOAI_106%E2%80%B3\" >De combien de poign\u00e9es est \u00e9quip\u00e9 le MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#A_quelle_pression_se_gonfle_le_MOAI_106%E2%80%B3\" >\u00c0 quelle pression se gonfle le MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#En_combien_de_temps_se_gonfle_le_MOAI_106%E2%80%B3\" >En combien de temps se gonfle le MOAI 10&rsquo;6&Prime; ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/moai-paddles\/moai-106\/#Conclusion_dois-je_acheter_le_MOAI_106%E2%80%B3\" >Conclusion : dois-je acheter le MOAI 10&rsquo;6&Prime; ?<\/a><\/li><\/ul><\/nav><\/div>\n\n\n\n\n<p>Le MOAI 10&rsquo;6&Prime; permet aux d\u00e9butants de se lancer dans le paddle avec beaucoup de stabilit\u00e9 gr\u00e2ce \u00e0 ses 81 cm de large et ses 15 cm d&rsquo;\u00e9paisseur. Il n&rsquo;est pas trop grand pour ne pas \u00eatre trop lent mais assez grand pour offrir un bon \u00e9quilibre. Il est donc parfait pour les d\u00e9butants. <\/p>\n\n\n\n<p>En plus de la planche, le package inclut un <strong>leash \u00e0 spirale, une pompe \u00e0 double action, un sac \u00e0 dos <\/strong>et un <strong>kit de r\u00e9paration. <\/strong>Il est important de souligner le design des paddles MOAI qui est vraiment superbe et qui a \u00e9t\u00e9 ex\u00e9cut\u00e9 par un designer reconnu. C&rsquo;est m\u00eame indiqu\u00e9 sur la valve : <strong>con\u00e7u aux Pays-Bas<\/strong>.  <\/p>\n\n\n\n<p>Au prix de 489 \u20ac (environ 529 $ actuellement), le  MOAI 10&rsquo;6&Prime; est un joli paddle tr\u00e8s correct qui apporte de la stabilit\u00e9 \u00e0 quiconque souhaite d\u00e9buter au paddle. Si vous voulez un peu plus de vitesse, jetez un coup d&rsquo;\u0153il au \u00ab\u00a0MOAI 11&prime;\u00a0\u00bb.<\/p>\n\n\n<div class=\"cegg5-container cegg-offers_grid\"><div class=\"container px-0 mb-5 mt-1\" >\n    <div class=\"row g-3 row-cols-2 row-cols-md-3 \">\n        \n                        \n<div class=\"col\">\n    <div class=\"cegg-grid-card card h-100 p-3 \">\n\n        \n        \n        \n                                <div class=\"ratio ratio-1x1 \">\n                <img class=\"card-img-top object-fit-scale rounded\" src=\"https:\/\/moaiboards.com\/wp-content\/uploads\/2021\/10\/sale-10.png\" decoding=\"async\" loading=\"lazy\" alt=\"MOAI SUP 10&#039;6\" title=\"\">            <\/div>\n        \n        <div class=\"card-body p-0 mt-2\">\n                            <div class=\"cegg-merchant small fs-6 text-body-secondary text-truncate\">\n                    <small>Moaiboards.com<\/small>\n                <\/div>\n            \n            \n            \n                <div class=\"cegg-card-price lh-1 pt-3 pb-2\">\n\n                    <div class=\"hstack gap-3\">\n\n                        <div>\n                            <span class=\"cegg-price fs-5 lh-1 mb-0\">\n                                &euro;359.00                            <\/span>\n\n                                                    <\/div>\n\n                        \n                    <\/div>\n\n                    \n                <\/div>\n            \n            \n                            <div class=\"card-title fs-6 fw-normal lh-base cegg-hover-title cegg-text-truncate-2 pt-2\">MOAI SUP 10&#039;6<\/div>            \n            \n            \n        <\/div>\n                    <div class=\"cegg-card-button pt-3\">\n                <div class=\"d-grid\">\n                    <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/moaiboards.com\/fr\/moai-106\/?ref=supworld\" class=\"stretched-link btn btn-outline-primary\">Click for best price<\/a>                <\/div>\n            <\/div>\n        \n    <\/div>\n<\/div>\n            <\/div>\n    \n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>Les plus<\/strong><\/p>\n\n\n\n<ul class=\"pro-list\">\n<li>Excellent paddle stable pour les novices<\/li>\n<li>Magnifique design de motifs tribaux<\/li>\n<li>Possibilit\u00e9 d&rsquo;installer un si\u00e8ge de kayak&nbsp;<\/li>\n<li>Un grand deck pad qui ne vous fait pas glisser de la planche<\/li>\n<li>Tous les accessoires inclus (sauf le si\u00e8ge de kayak)<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>Les moins<\/strong><\/p>\n\n\n\n<ul class=\"con-list\">\n<li>Pas de kick pad<\/li>\n<li>La pagaie fournie est en aluminium<\/li>\n<li>Une seule poign\u00e9e de transport<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Board-1024x768.jpg\" alt=\"Paddle MOAI10&#039;6\" class=\"wp-image-23390\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Board-1024x768.jpg 1024w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Board-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Board-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Board-702x526.jpg 702w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Board.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Le_MOAI_106%E2%80%B3_convient_surtout_pour\"><\/span>Le MOAI 10&rsquo;6&Prime; convient surtout pour :<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Le MOAI 10&rsquo;6&Prime; est un excellent paddle de  qualit\u00e9 fourni avec un package complet. C&rsquo;est le plus petit et le plus large des <a href=\"https:\/\/standuppaddleboardworld.com\/fr\/paddles-gonflables-moai\/\" class=\"rank-math-link\">paddles MOAI<\/a> qui comprennent \u00e9galement le \u00ab\u00a0MOAI 11&prime;\u00a0\u00bb et le \u00ab\u00a0MOAI 12&rsquo;6&Prime;\u00a0\u00bb. (Et bient\u00f4t \u00e9galement le <strong>MOAI 9&rsquo;5\u2033 <\/strong>et le <strong>MOAI 12&rsquo;4\u2033<\/strong> !)<\/p>\n\n\n\n<p>Ce paddle est polyvalent et donc adapt\u00e9 \u00e0 toutes les activit\u00e9s de paddle dont vous avez envie. Le paddle indique un poids max. de <strong>130 kg<\/strong>. Avec mon poids de 80 kg, il ne s&rsquo;est pas du tout courb\u00e9 et \u00e9tait tr\u00e8s rigide.  <\/p>\n\n\n\n<p>Il n&rsquo;est pas recommand\u00e9 pour pagayer \u00e0 deux \u00e0 moins d&rsquo;\u00eatre tr\u00e8s l\u00e9ger. MOAI va bient\u00f4t sortir le <strong>paddle MOAI 12&rsquo;4&Prime; <\/strong>qui est justement con\u00e7u pour \u00e7a. <\/p>\n\n\n\n<p>Ce paddle tr\u00e8s stable mesure <strong>320 cm de long et 81 cm de large. <\/strong>C&rsquo;est la raison pour laquelle il convient tout particuli\u00e8rement aux d\u00e9butants, les risques de chute \u00e9tant limit\u00e9s. Les <strong>15 cm d&rsquo;\u00e9paisseur <\/strong>confortent la stabilit\u00e9 et assurent que le paddle ne se courbe pas au milieu. <\/p>\n\n\n\n<p>Avec ses dimensions et son nez arrondi, vous n&rsquo;atteindrez pas des records de vitesse mais vous pouvez pagayer en toute d\u00e9tente \u00e0 un bon rythme. Si vous cherchez \u00e0 aller plus vite, jetez un coup d&rsquo;\u0153il au <strong>MOAI 11&prime;<\/strong>, que j&rsquo;ai d\u00e9j\u00e0 mentionn\u00e9, et au <strong>MOAI 12&rsquo;6&Prime;<\/strong>.<\/p>\n\n\n\n<p>Le MOAI 10&rsquo;6&Prime; offre un bon rapport qualit\u00e9-prix et est fourni avec tous les accessoires n\u00e9cessaires pour commencer directement.<\/p>\n\n\n\n<p>Ce que j&rsquo;aime le plus chez MOAI, c&rsquo;est leur <strong>magnifique design <\/strong>et le fait qu&rsquo;ils donnent une partie de leurs b\u00e9n\u00e9fices \u00e0 <a aria-label=\"Waves For Change (opens in a new tab)\" href=\"https:\/\/www.waves-for-change.org\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"rank-math-link\">Waves For Change<\/a> pour aider \u00e0 changer des vies en Afrique et \u00e0 am\u00e9liorer l&rsquo;avenir de certains enfants l\u00e0-bas. C&rsquo;est une noble cause et un tr\u00e8s beau geste d&rsquo;aider au lieu de simplement engranger les b\u00e9n\u00e9fices.<br><br><strong>Si vous \u00eates d\u00e9butant et recherchez un paddle gonflable pour vous lancer, le MOAI 10&rsquo;6&Prime; est un package excellent et complet de tr\u00e8s bonne qualit\u00e9 et dot\u00e9 d&rsquo;un tr\u00e8s beau design.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background\" style=\"background-color:#f3f4f5\"><tbody><tr><td><strong>Longueur<\/strong><\/td><td><strong>Largeur<\/strong><\/td><td><strong>\u00c9paisseur<\/strong><\/td><td><strong>Charge utile max.<\/strong><\/td><td><strong>Poids paddle<\/strong><\/td><\/tr><tr><td> 320 cm<\/td><td>81 cm<\/td><td>15 cm<\/td><td>130 kg<\/td><td>11 kg<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/primary-use-board.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Utilisations principales<\/strong><br>Polyvalente \/ D\u00e9tente \/ Yoga \/ Animaux<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/speed-paddleboard.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Vitesse sur l&rsquo;eau<\/strong><br>Le paddle est con\u00e7u pour \u00eatre stable et polyvalent, la vitesse n&rsquo;est donc pas la priorit\u00e9 mais il est tout de m\u00eame assez fin pour pouvoir atteindre un bon rythme de croisi\u00e8re.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/transport-standuppaddleboard.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Transport<\/strong><br>Le paddle p\u00e8se 11 kg et n&rsquo;est pas difficile \u00e0 transporter dans le sac \u00e0 dos fourni et \u00e9quip\u00e9 d&rsquo;une d&rsquo;attache pratique devant.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/stability-board.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Stabilit\u00e9<\/strong><br>Les 81 cm de large rendent le paddle plus stable qu&rsquo;une planche moyenne de 76 cm, ce qui est pratique pour les d\u00e9butants. Les 15 cm  d&rsquo;\u00e9paisseur et les mat\u00e9riaux solides ajoutent \u00e9galement de la stabilit\u00e9 et du soutien.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mon_experience\"><\/span>Mon exp\u00e9rience<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Quand j&rsquo;ai re\u00e7u le colis, j&rsquo;\u00e9tais impatient de le d\u00e9baller, de gonfler le paddle et de me lancer \u00e0 l&rsquo;eau en ce jour vraiment ensoleill\u00e9. Les <strong>accessoires semblent tous de bonne qualit\u00e9<\/strong> mais je n&rsquo;avais pas h\u00e2te de retourner \u00e0 une pagaie en aluminium apr\u00e8s avoir essay\u00e9 toutes <a href=\"https:\/\/standuppaddleboardworld.com\/fr\/pagaies-de-paddle\/\" class=\"rank-math-link\">ces pagaies en fibre de verre et en carbone<\/a>. <\/p>\n\n\n\n<p>Je vous joins une vid\u00e9o acc\u00e9l\u00e9r\u00e9e me montrant entrain de gonfler le MOAI 10&rsquo;6&Prime; de toutes mes forces. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"How to inflate the MOAI 10&#039;6&quot; Stand Up Paddle Board\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/HWcO_vcV95g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption>Me voici en train de pomper comme un forcen\u00e9, 4 minutes 25 secondes pour gonfler la planche<\/figcaption><\/figure>\n\n\n\n<p>Quand j&rsquo;ai d\u00e9ball\u00e9 le paddle, il y avait pas mal de choses \u00e0 d\u00e9couvrir. J&rsquo;aime le <strong>design de style tribal <\/strong>imprim\u00e9 sur le nez du paddle, le sac \u00e0 dos, le leash et la pagaie.  C&rsquo;est <strong>l&rsquo;un des designs de paddle les plus sympa du march\u00e9<\/strong> et il a \u00e9t\u00e9 visiblement tr\u00e8s soign\u00e9. Ceci dit, \u00e7a reste une question de go\u00fbt.<\/p>\n\n\n\n<p>Apr\u00e8s le d\u00e9ballage, j&rsquo;ai commenc\u00e9 \u00e0 gonfler le MOAI 10&rsquo;6&Prime; comme vous avez pu le voir sur la vid\u00e9o. Il m&rsquo;a fallu <strong>4 minutes et 25 secondes pour le gonfler enti\u00e8rement <\/strong>\u00e0 1 bar, ce qui est un bon temps. Si vous y allez plus tranquillement, il vous faudra 6 minutes environ. <br><em><br>Vous pensez pouvoir faire mieux ? Avis aux vid\u00e9os \ud83d\ude09<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"MOAI SUP boards | Review by Stand up Paddle board world\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/io9qr21CnSs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Le MOAI 10&rsquo;6&Prime; p\u00e8se 11 kg ce qui en fait un paddle tr\u00e8s l\u00e9ger et facile \u00e0 porter jusqu&rsquo;\u00e0 l&rsquo;eau. Quand j&rsquo;ai commenc\u00e9 \u00e0 pagayer, je me suis senti <strong>tr\u00e8s en s\u00e9curit\u00e9 <\/strong>comme s&rsquo;il \u00e9tait impossible que je tombe \u00e0 l&rsquo;eau. La planche ne bougeait pas du tout, je la recommande donc vraiment \u00e0 quiconque veut se mettre au paddle. <\/p>\n\n\n\n<p>Ce jour-l\u00e0, j&rsquo;ai pris tous les paddles de MOAI pour les essayer, le <strong>MOAI 10&rsquo;6&Prime;<\/strong>, le <strong>MOAI 11&prime;<\/strong> et le <strong>MOAI 12&rsquo;6&Prime;<\/strong>. <\/p>\n\n\n\n<p>La pagaie en alu est un peu plus lourde que les pagaies que j&rsquo;avais essay\u00e9es avant, j&rsquo;ai donc pagay\u00e9 un peu plus lentement pour compenser. Par contre, j&rsquo;aime beaucoup le <strong>super design <\/strong>et <strong>l&rsquo;indicateur de longueur clair sur le manche de la pagaie.<\/strong> <\/p>\n\n\n\n<p>Le <strong>sandow \u00e0 l&rsquo;avant <\/strong>du paddle offre assez d&rsquo;espace pour prendre tout l&rsquo;\u00e9quipement n\u00e9cessaire, de l&rsquo;eau et des snacks (les bananes et les noix sont ma nourriture pr\u00e9f\u00e9r\u00e9e sur un paddle). Bien s\u00fbr, j&rsquo;avais mis mes affaires dans un \u00ab\u00a0sac \u00e9tanche\u00a0\u00bb pour \u00eatre s\u00fbr qu&rsquo;elles ne prennent pas l&rsquo;eau ou ne glissent pas par-dessus bord.  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-1024x768.jpg\" alt=\"Nez MOAI 10&#039;6&quot;\" class=\"wp-image-23392\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-1024x768.jpg 1024w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-702x526.jpg 702w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>Le grand deck pad \u00e9tait tr\u00e8s bien et confortable sous mes pieds. Le <strong>deck pad diamond anti-d\u00e9rapant <\/strong>est tr\u00e8s courant sur les paddles et on comprend pourquoi. J&rsquo;aime la <strong>possibilit\u00e9 de pouvoir installer un si\u00e8ge de kayak <\/strong>sur le paddle, mais \u00e9tant donn\u00e9 que j&rsquo;ai \u00e9t\u00e9 tr\u00e8s g\u00e2t\u00e9 ces derniers temps, j&rsquo;ai \u00e9t\u00e9 un peu d\u00e9\u00e7u qu&rsquo;il ne soit pas inclus dans le package. Ce qui n&rsquo;est pas logique bien s\u00fbr car ce n&rsquo;est pas indispensable pour commencer le paddle. <\/p>\n\n\n\n<p>Comme je le disais, j&rsquo;ai pagay\u00e9 un peu plus lentement \u00e0 cause du poids de la pagaie mais la planche \u00e9tait tr\u00e8s stable et facile \u00e0 diriger. Avec ses <strong>3 ailerons<\/strong>, je n&rsquo;avais \u00e9galement pas de difficult\u00e9 \u00e0 pagayer en ligne droite si je le voulais, elle est donc parfaite \u00e0 ce niveau l\u00e0. <\/p>\n\n\n\n<p>Par ailleurs, le paddle semble <strong>bien \u00e9quip\u00e9 pour pagayer assis <\/strong>mais il vous faut une autre pagaie 2-en-1 et un si\u00e8ge de kayak pour un co\u00fbt additionnel de 95 \u20ac. Si c&rsquo;est vraiment ce que vous voulez faire, vous avez int\u00e9r\u00eat \u00e0 acheter le <a href=\"https:\/\/standuppaddleboardworld.com\/fr\/bluefin\/evaluation-du-bluefin-cruise\/\" class=\"rank-math-link\">Bluefin Cruise<\/a> qui inclut ces accessoires et vous permet de vous y mettre tout de suite \u00e0 un prix moins \u00e9lev\u00e9 au total. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"MOAI brand movie 2019_wo\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/bA7OCiAXsS8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>C&rsquo;est sans aucun doute un joli paddle pour d\u00e9butants, et si vous appr\u00e9ciez son design et sa configuration, vous vous amuserez beaucoup avec. La qualit\u00e9 est bonne et je pense que ce paddle n&rsquo;est pas pr\u00e8s de casser. Il y a une <strong>garantie d&rsquo;1 an sur la planche<\/strong>, ce qui est plut\u00f4t standard. Ne vous habituez pas trop aux 5 ans de garantie offerts par Red Paddle et Bluefin !<\/p>\n\n\n\n<p>Si vous aimez vraiment la planche mais recherchez un mod\u00e8le un peu plus rapide ou con\u00e7u pour de longues balades, jetez un coup d&rsquo;\u0153il au <strong>MOAI 11&prime; <\/strong>ou au <strong>MOAI 12&rsquo;6&Prime;. <\/strong><\/p>\n\n\n<div class=\"cegg5-container cegg-offers_grid\"><div class=\"container px-0 mb-5 mt-1\" >\n    <div class=\"row g-3 row-cols-2 row-cols-md-3 \">\n        \n                        \n<div class=\"col\">\n    <div class=\"cegg-grid-card card h-100 p-3 \">\n\n        \n        \n        \n                                <div class=\"ratio ratio-1x1 \">\n                <img class=\"card-img-top object-fit-scale rounded\" src=\"https:\/\/moaiboards.com\/wp-content\/uploads\/2021\/10\/sale-10.png\" decoding=\"async\" loading=\"lazy\" alt=\"MOAI SUP 10&#039;6\" title=\"\">            <\/div>\n        \n        <div class=\"card-body p-0 mt-2\">\n                            <div class=\"cegg-merchant small fs-6 text-body-secondary text-truncate\">\n                    <small>Moaiboards.com<\/small>\n                <\/div>\n            \n            \n            \n                <div class=\"cegg-card-price lh-1 pt-3 pb-2\">\n\n                    <div class=\"hstack gap-3\">\n\n                        <div>\n                            <span class=\"cegg-price fs-5 lh-1 mb-0\">\n                                &euro;359.00                            <\/span>\n\n                                                    <\/div>\n\n                        \n                    <\/div>\n\n                    \n                <\/div>\n            \n            \n                            <div class=\"card-title fs-6 fw-normal lh-base cegg-hover-title cegg-text-truncate-2 pt-2\">MOAI SUP 10&#039;6<\/div>            \n            \n            \n        <\/div>\n                    <div class=\"cegg-card-button pt-3\">\n                <div class=\"d-grid\">\n                    <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/moaiboards.com\/fr\/moai-106\/?ref=supworld\" class=\"stretched-link btn btn-outline-primary\">Click for best price<\/a>                <\/div>\n            <\/div>\n        \n    <\/div>\n<\/div>\n            <\/div>\n    \n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Tail-1024x768.jpg\" alt=\"\" data-id=\"6516\" data-full-url=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Tail.jpg\" data-link=\"https:\/\/standuppaddleboardworld.com\/?attachment_id=6516\" class=\"wp-image-23391\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Tail-1024x768.jpg 1024w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Tail-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Tail-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Tail-702x526.jpg 702w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Tail.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-1024x768.jpg\" alt=\"\" data-id=\"6519\" data-full-url=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose.jpg\" data-link=\"https:\/\/standuppaddleboardworld.com\/?attachment_id=6519\" class=\"wp-image-23392\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-1024x768.jpg 1024w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose-702x526.jpg 702w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Nose.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Middle-1024x768.jpg\" alt=\"\" data-id=\"6522\" data-full-url=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Middle.jpg\" data-link=\"https:\/\/standuppaddleboardworld.com\/?attachment_id=6522\" class=\"wp-image-23393\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Middle-1024x768.jpg 1024w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Middle-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Middle-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Middle-702x526.jpg 702w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Middle.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Fins-1024x768.jpg\" alt=\"\" data-id=\"6525\" data-full-url=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Fins.jpg\" data-link=\"https:\/\/standuppaddleboardworld.com\/?attachment_id=6525\" class=\"wp-image-23394\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Fins-1024x768.jpg 1024w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Fins-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Fins-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Fins-702x526.jpg 702w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Fins.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Back-1024x768.jpg\" alt=\"\" data-id=\"6528\" data-full-url=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Back.jpg\" data-link=\"https:\/\/standuppaddleboardworld.com\/?attachment_id=6528\" class=\"wp-image-23395\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Back-1024x768.jpg 1024w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Back-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Back-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Back-702x526.jpg 702w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-10-6-Back.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Principales_caracteristiques\"><\/span>Principales caract\u00e9ristiques<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/sup-setup.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Configuration<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Poign\u00e9e centrale<\/strong>&nbsp;\u2013 Le paddle est \u00e9quip\u00e9 d&rsquo;une poign\u00e9e centrale pour le transporter facilement \u00e0 l&rsquo;eau une fois gonfl\u00e9.<\/li><li><strong>Anneaux en D &amp; filet \u00e0 bagages<\/strong>&nbsp;\u2013 Le paddle compte plusieurs anneaux en D. \u00c0 l&rsquo;avant, vous avez un filet \u00e0 bagages cr\u00e9\u00e9 avec un cordon de leash et 4 anneaux en D. C&rsquo;est id\u00e9al si vous voulez prendre du mat\u00e9riel suppl\u00e9mentaire, tel qu&rsquo;un sac \u00e9tanche. Vous pouvez attacher un leash pour surfer \u00e0 l&rsquo;anneau en D \u00e0 l&rsquo;arri\u00e8re de la planche. Au centre, il y a 4 anneaux en D additionnels pour le <strong>si\u00e8ge kayak optionnel <\/strong>(non inclus).<\/li><li><strong>Deck pad confortable <\/strong>\u2013 Le deck pad est en mousse matelass\u00e9e confortable pour les pieds et dot\u00e9 d&rsquo;un relief en diamant pour une meilleure adh\u00e9rence.<\/li><li><strong>Aileron d\u00e9tachable<\/strong>&nbsp;\u2013 Le paddle dispose d&rsquo;un syst\u00e8me de 3 ailerons dont le grand aileron central facile \u00e0 enlever.<\/li><\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/fin-paddleboard.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Ailerons<\/strong><br>Le MOAI 10&rsquo;6&Prime; est \u00e9quip\u00e9 de trois ailerons pour fournir plus de stabilit\u00e9, le plus grand des trois au milieu est amovible pour un rangement facile.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/material-paddleboard.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Mat\u00e9riaux<\/strong><br>Le MOAI 10&rsquo;6&Prime; est en <strong>mat\u00e9riau drop stitch tr\u00e8s robuste <\/strong>avec une double couche en PVC. Les dizaines de milliers de mailles en polyester en font un paddle tr\u00e8s robuste, rigide et dur comme de la pierre.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/inflation-time-paddleboard.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Gonflage \/ D\u00e9gonflage<\/strong><br>Le MOAI 10&rsquo;6&Prime; se gonfle en 4,5 minutes avec la pompe \u00e0 double action fournie.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/warranty-sup.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Garantie<\/strong><br>1 an de garantie sur les d\u00e9fauts de fabrication<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-large is-resized image-circle\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/themes\/genesis-sample\/icons\/design-supboard.svg\" alt=\"\" width=\"107\" height=\"107\" title=\"\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p><strong>Design<\/strong><br>Tr\u00e8s \u00e9l\u00e9gant et moderne et joliment con\u00e7u par un designer reconnu aux Pays-Bas !<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Inclus_dans_le_package\"><\/span>Inclus dans le package<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p style=\"font-size:28px\"><strong>La pagaie<\/strong><\/p>\n\n\n\n<p>La pagaie incluse avec le paddle est une pagaie MOAI standard. Cette pagaie en <strong>aluminium est de bonne qualit\u00e9 et r\u00e9glable. <\/strong>Sa hauteur s&rsquo;ajuste gr\u00e2ce \u00e0 l&rsquo;<strong>indicateur de longueur <\/strong>sur le manche. <\/p>\n\n\n\n<p>Elle est constitu\u00e9e de 3 pi\u00e8ces pour faciliter le transport et est d\u00e9cor\u00e9e avec les motifs tribaux de MOAI sur la pale. J&rsquo;adore le fait que le design de la pale et celui du paddle soient accord\u00e9s, pas vous ?<\/p>\n\n\n\n<p class=\"block-more-info\">Vous pr\u00e9f\u00e9rez une pagaie en fibre de verre ou en carbone ? Lisez mon guide sur les <a class=\"rank-math-link\" href=\"https:\/\/standuppaddleboardworld.com\/fr\/pagaies-de-paddle\/\">meilleures pagaies de paddle en 2022<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"881\" height=\"1000\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/MOAIstandardpaddle.jpg\" alt=\"MOAIstandardpaddle\" data-id=\"461\" data-full-url=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/MOAIstandardpaddle.jpg\" data-link=\"https:\/\/standuppaddleboardworld.com\/moai\/moai-11-stand-up-paddle-board\/moaistandardpaddle\/\" class=\"wp-image-23490\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/MOAIstandardpaddle.jpg 881w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/MOAIstandardpaddle-264x300.jpg 264w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/MOAIstandardpaddle-768x872.jpg 768w\" sizes=\"auto, (max-width: 881px) 100vw, 881px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Paddle-Design-1.jpg\" alt=\"\" data-id=\"5825\" data-full-url=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Paddle-Design-1.jpg\" data-link=\"https:\/\/standuppaddleboardworld.com\/moai\/moai-11-stand-up-paddle-board\/moai-paddle-design-1-2\/\" class=\"wp-image-5825\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Paddle-Design-1.jpg 1000w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Paddle-Design-1-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Paddle-Design-1-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Paddle-Design-1-702x526.jpg 702w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p style=\"font-size:28px\"><strong>La pompe<\/strong><\/p>\n\n\n\n<p>MOAI a inclus une pompe \u00e0 double action dans le package, et elle semble bien fonctionner. Quand je l&rsquo;ai essay\u00e9e, il m&rsquo;a fallu seulement <strong>4 minutes et 25 secondes <\/strong>pour gonfler la planche \u00e0 la pression souhait\u00e9e d&rsquo;1 bar. \u00c0 un rythme plus tranquille, il faut probablement environ 6 minutes. <\/p>\n\n\n\n<p class=\"block-more-info\">Si vous voulez savoir quelle est la meilleure pompe, d\u00e9couvrez mon article sur les <a href=\"https:\/\/standuppaddleboardworld.com\/fr\/pompes-de-paddle\/\" class=\"rank-math-link\">meilleures pompes de paddle en 2020<\/a><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Pump.jpg\" alt=\"MOAI-SUP-Pump\" class=\"wp-image-23513\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Pump.jpg 1000w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Pump-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Pump-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Pump-702x526.jpg 702w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<p style=\"font-size:28px\"><strong>Le leash<\/strong><\/p>\n\n\n\n<p>MOAI a inclus son leash de s\u00e9curit\u00e9 avec le paddle. C&rsquo;est un <strong>leash \u00e0 spirale<\/strong> qui s&rsquo;\u00e9tend uniquement si vous tombez \u00e0 l&rsquo;eau. Vous pouvez l&rsquo;attacher \u00e0 votre cheville avec le velcro, et la construction de broches en aluminium est robuste. La bande est dot\u00e9e d&rsquo;un <strong>rembourrage \u00e9pais sympa <\/strong>pour le confort de votre cheville et pour ne pas irriter votre peau. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Leash.jpg\" alt=\"MOAI-SUP-Leash\" class=\"wp-image-23509\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Leash.jpg 1000w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Leash-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Leash-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-SUP-Leash-702x526.jpg 702w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<p style=\"font-size:28px\"><strong>Le sac \u00e0 dos<\/strong><\/p>\n\n\n\n<p>Le sac \u00e0 dos de MOAI est tr\u00e8s confortable et offre un joli design accord\u00e9 avec le paddle. Il a une petite <strong>pochette \u00e0 fermeture \u00e9clair <\/strong>pratique sur le devant. Ce <strong>sac \u00e0 dos est \u00e9quip\u00e9 de roulettes <\/strong>pour faciliter le transport sur les surfaces r\u00e9guli\u00e8res ainsi que de poign\u00e9es au-dessus et sur les c\u00f4t\u00e9s, mais vous utiliserez surtout les<strong> sangles et l&rsquo;attache frontale pratique<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack-Tom.jpg\" alt=\"MOAI-Backpack-Tom\" data-id=\"5811\" data-full-url=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack-Tom.jpg\" data-link=\"https:\/\/standuppaddleboardworld.com\/moai\/moai-11-stand-up-paddle-board\/moai-backpack-tom\/\" class=\"wp-image-23511\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack-Tom.jpg 1000w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack-Tom-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack-Tom-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack-Tom-702x526.jpg 702w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack.jpg\" alt=\"MOAI-Backpack\" data-id=\"5808\" data-full-url=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack.jpg\" data-link=\"https:\/\/standuppaddleboardworld.com\/moai\/moai-11-stand-up-paddle-board\/moai-backpack\/\" class=\"wp-image-23510\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack.jpg 1000w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-Backpack-702x526.jpg 702w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Accessoires_optionnels_non_inclus\"><\/span>Accessoires optionnels (non inclus)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"wp-block-columns block-products is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/restube-classic_1.jpg\" alt=\"Restube Classic\" class=\"wp-image-23495\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/restube-classic_1.jpg 500w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/restube-classic_1-300x300.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/restube-classic_1-150x150.jpg 150w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2019\/12\/restube-classic_1-75x75.jpg 75w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<p><strong>Restube classic<\/strong><br>Un kit de secours car on n\u2019est jamais trop prudent !<\/p>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-text-color has-background\" href=\"https:\/\/geni.us\/restube-classic\" style=\"background-color:#1db8fb;color:#ffffff\" target=\"_blank\" rel=\"noopener\">Acheter Restube Classic<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/moai-kajak-zitje.jpg\" alt=\"\" class=\"wp-image-23389\" width=\"382\" height=\"348\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/moai-kajak-zitje.jpg 548w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/moai-kajak-zitje-300x274.jpg 300w\" sizes=\"auto, (max-width: 382px) 100vw, 382px\" \/><\/figure>\n\n\n\n<p><strong>Si\u00e8ge kayak MOAI<\/strong><br>Si vous voulez pagayer assis.<\/p>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-text-color has-background\" href=\"https:\/\/geni.us\/moai-kayak-seat\" style=\"background-color:#1db8fb;color:#ffffff\" target=\"_blank\" rel=\"noreferrer noopener\">Acheter le si\u00e8ge kayak MOAI<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Differences_entre_un_paddle_gonflable_et_un_paddle_rigide\"><\/span>Diff\u00e9rences entre un paddle gonflable et un paddle rigide<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns block-products is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>Avantages paddle gonflable<\/strong><\/p>\n\n\n\n<ul class=\"pro-list\">\n<li>Facile \u00e0 emporter en vacances (m\u00eame \u00e0 bord d&rsquo;un avion)<\/li>\n<li>Facile \u00e0 ranger en hiver<\/li>\n<li>Bien moins cher<\/li>\n<li>La technologie s&rsquo;est beaucoup am\u00e9lior\u00e9e ces 10 derni\u00e8res ann\u00e9es, \u00e0 tel&nbsp;point que ces planches sont d\u00e9sormais <span style=\"text-decoration: underline;\">difficiles \u00e0 diff\u00e9rencier des planches rigides<\/span><\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>Avantages paddle rigide<\/strong><\/p>\n\n\n\n<ul class=\"pro-list\">\n<li>Plus rapide, ce qui est important pour un pro<\/li>\n<li>Facilite les virages serr\u00e9s sur l&rsquo;eau du fait des bords plus fins<\/li>\n<li>Pas besoin de le gonfler, vous allez \u00e0 l&rsquo;eau directement<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/moai-sup-boards-1024x683.jpg\" alt=\"Paddle MOAI\" class=\"wp-image-15295\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/moai-sup-boards-1024x683.jpg 1024w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/moai-sup-boards-300x200.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/moai-sup-boards-768x512.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/moai-sup-boards-1536x1024.jpg 1536w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/moai-sup-boards-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"cegg5-container cegg-offers_grid\"><div class=\"container px-0 mb-5 mt-1\" >\n    <div class=\"row g-3 row-cols-2 row-cols-md-3 \">\n        \n                        \n<div class=\"col\">\n    <div class=\"cegg-grid-card card h-100 p-3 \">\n\n        \n        \n        \n                                <div class=\"ratio ratio-1x1 \">\n                <img class=\"card-img-top object-fit-scale rounded\" src=\"https:\/\/moaiboards.com\/wp-content\/uploads\/2021\/10\/sale-10.png\" decoding=\"async\" loading=\"lazy\" alt=\"MOAI SUP 10&#039;6\" title=\"\">            <\/div>\n        \n        <div class=\"card-body p-0 mt-2\">\n                            <div class=\"cegg-merchant small fs-6 text-body-secondary text-truncate\">\n                    <small>Moaiboards.com<\/small>\n                <\/div>\n            \n            \n            \n                <div class=\"cegg-card-price lh-1 pt-3 pb-2\">\n\n                    <div class=\"hstack gap-3\">\n\n                        <div>\n                            <span class=\"cegg-price fs-5 lh-1 mb-0\">\n                                &euro;359.00                            <\/span>\n\n                                                    <\/div>\n\n                        \n                    <\/div>\n\n                    \n                <\/div>\n            \n            \n                            <div class=\"card-title fs-6 fw-normal lh-base cegg-hover-title cegg-text-truncate-2 pt-2\">MOAI SUP 10&#039;6<\/div>            \n            \n            \n        <\/div>\n                    <div class=\"cegg-card-button pt-3\">\n                <div class=\"d-grid\">\n                    <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/moaiboards.com\/fr\/moai-106\/?ref=supworld\" class=\"stretched-link btn btn-outline-primary\">Click for best price<\/a>                <\/div>\n            <\/div>\n        \n    <\/div>\n<\/div>\n            <\/div>\n    \n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Autres_revues_en_ligne_sur_le_MOAI_106%E2%80%B3\"><\/span>Autres revues en ligne sur le MOAI 10&rsquo;6&Prime;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Le MOAI 10&rsquo;6&Prime; est un paddle relativement r\u00e9cent sur internet, il n&rsquo;a donc pas encore beaucoup d&rsquo;\u00e9valuations.<\/p>\n\n\n\n<p>Voici un aper\u00e7u de celles que j&rsquo;ai trouv\u00e9es :<\/p>\n\n\n\n<p><strong>Supboard-99.co.uk :<\/strong> Score 8,8\/10. \u00ab\u00a0Globalement, le MOAI est un super paddle pour les (jeunes) adultes qui veulent se balader avec leur planche. Vous pouvez \u00e9galement vous d\u00e9tendre, faire du yoga ou du kayak sur ce paddle polyvalent. Selon nous, une vraie planche polyvalente que nous recommandons \u00e0 tout le monde !\u00a0\u00bb<\/p>\n\n\n\n<p><strong>Abonnietravelersinsideguide.com :<\/strong> \u00ab\u00a0J&rsquo;ai essay\u00e9 de r\u00e9veiller la Vaiana qui sommeille en moi cet \u00e9t\u00e9 sur le MOAI 10\u20196 et je ne peux que le recommander \u00e0 tous ceux qui cherchent un paddle. C&rsquo;est une planche de tr\u00e8s bonne qualit\u00e9 avec une super stabilit\u00e9 et tr\u00e8s polyvalente, parfaite pour les d\u00e9butants. J&#8217;emm\u00e8ne souvent mes amis et ma famille faire un tour pour leur faire d\u00e9couvrir le paddle et ils sont tous d&rsquo;accord sur le fait que le MOAI est super stable et facile \u00e0 man\u0153uvrer en comparaison avec les autres marques. Ce paddle est incroyablement robuste sur l&rsquo;eau et sa grande surface permet de garder l&rsquo;\u00e9quilibre et une posture confortable.\u00a0\u00bb<\/p>\n\n\n\n<p><strong>Amazon.co.uk : <\/strong> Score 4,3\/5. \u00ab\u00a0Le paddle a \u00e9t\u00e9 livr\u00e9 rapidement et \u00e7a fait deux semaines que je l&rsquo;utilise sur un lac. Il se gonfle et se range tr\u00e8s bien (il rentre facilement dans le sac \u00e0 dos et la fermeture \u00e9clair est ok). Il supporte deux personnes d&rsquo;un poids max de 155 kg sans avoir les pieds mouill\u00e9s.\u00a0\u00bb &#8211; Sur la base de 5 \u00e9valuations client au 14 mai 2020.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-paddle-board-bottom-1024x768.jpg\" alt=\"\" class=\"wp-image-23397\" title=\"\" srcset=\"https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-paddle-board-bottom-1024x768.jpg 1024w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-paddle-board-bottom-300x225.jpg 300w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-paddle-board-bottom-768x576.jpg 768w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-paddle-board-bottom-702x526.jpg 702w, https:\/\/standuppaddleboardworld.com\/wp-content\/uploads\/2020\/05\/MOAI-paddle-board-bottom.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Questions_frequentes_a_propos_du_MOAI_106%E2%80%B3\"><\/span>Questions fr\u00e9quentes \u00e0 propos du MOAI 10&rsquo;6&Prime;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1584708226813\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Combien_mesure_le_MOAI_106%E2%80%B3\"><\/span>Combien mesure le MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Longueur : 320 cm, Largeur : 81 cm, \u00c9paisseur : 15 cm <\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1584708281884\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Quelle_est_la_capacite_de_charge_maximale_du_MOAI_106%E2%80%B3\"><\/span>Quelle est la capacit\u00e9 de charge maximale du MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>130 kg<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1584708303722\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Quest-ce_qui_est_inclus_avec_le_MOAI_106%E2%80%B3\"><\/span>Qu&rsquo;est-ce qui est inclus avec le MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Le sac \u00e0 dos premium MOAI, une pagaie aluminium r\u00e9glable en hauteur, un leash \u00e0 spirale MOAI, une pompe manuelle \u00e0 double action, un kit de r\u00e9paration<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1584708336386\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Combien_pese_le_MOAI_106%E2%80%B3\"><\/span>Combien p\u00e8se le MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>11 kg<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1584708385713\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"De_combien_dailerons_est_equipe_le_MOAI_106%E2%80%B3\"><\/span>De combien d&rsquo;ailerons est \u00e9quip\u00e9 le MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>3 ailerons, 2 petits et un grand d\u00e9montable<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1584708403149\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"De_combien_danneaux_en_D_est_equipe_le_MOAI_106%E2%80%B3\"><\/span>De combien d&rsquo;anneaux en D est \u00e9quipe le MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>9 anneaux en D,  un sandow \u00e0 l&rsquo;avant, un pour attacher le leash, 4 pour le si\u00e8ge de kayak en option.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1586526110301\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Quelle_est_la_duree_de_garantie_du_MOAI_106%E2%80%B3\"><\/span>Quelle est la dur\u00e9e de garantie du MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>La garantie de ce paddle est d&rsquo;1 an<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1586526273343\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Le_MOAI_106%E2%80%B3_est-il_equipe_dun_support_de_GoPro\"><\/span>Le MOAI 10&rsquo;6&Prime; est-il \u00e9quip\u00e9 d&rsquo;un support de GoPro ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Non<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1586526326180\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"De_combien_de_poignees_est_equipe_le_MOAI_106%E2%80%B3\"><\/span>De combien de poign\u00e9es est \u00e9quip\u00e9 le MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Il a une poign\u00e9e centrale<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1586526358109\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"A_quelle_pression_se_gonfle_le_MOAI_106%E2%80%B3\"><\/span>\u00c0 quelle pression se gonfle le MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Il se gonfle jusqu&rsquo;\u00e0 1 bar<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1588670570465\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"En_combien_de_temps_se_gonfle_le_MOAI_106%E2%80%B3\"><\/span>En combien de temps se gonfle le MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Environ 4,5 minutes avec la pompe \u00e0 double action fournie<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion_dois-je_acheter_le_MOAI_106%E2%80%B3\"><\/span>Conclusion : dois-je acheter le MOAI 10&rsquo;6&Prime; ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-group block-conclusion\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p>Le MOAI 10&rsquo;6&Prime; est un <strong>paddle tr\u00e8s stable <\/strong>et de <strong>tr\u00e8s bonne qualit\u00e9<\/strong> fourni avec un package complet pour commencer directement. Le <strong>joli design <\/strong>et le fait qu&rsquo;une <strong>partie des b\u00e9n\u00e9fices vont \u00e0 une association caritative <\/strong>ajoutent sans aucun doute au charme de cette planche.<\/p>\n\n\n\n<p>En ce qui concerne le package, j&rsquo;aurais pr\u00e9f\u00e9r\u00e9 qu&rsquo;il y ait autre chose qu&rsquo;une pagaie en aluminium, et un kick pad, mais je comprends tout \u00e0 fait que le kick pad ne soit pas la cible, ce paddle \u00e9tant con\u00e7u pour la d\u00e9tente. D&rsquo;autre part, \u00e9tant donn\u00e9 que la planche co\u00fbte moins de 500 \u20ac, c&rsquo;est normal que la pagaie soit en aluminium, elle fonctionne bien malgr\u00e9 tout et les d\u00e9butants ne feront pas le diff\u00e9rence. <br><br>Comme je n&rsquo;ai cess\u00e9 de le dire dans cet article, le MOAI 10&rsquo;6&Prime; est un paddle tr\u00e8s confortable pour les novices qui se lancent dans le paddle, et il offre un package d&rsquo;accessoires complet et de bonne qualit\u00e9. Une planche tr\u00e8s rigide et stable, une <strong>pagaie ajustable en hauteur, une pompe manuelle \u00e0 double action, un leash \u00e0 spirale, un kit de r\u00e9paration, 9 anneaux en D, <\/strong>un <strong>grand deck pad et 3 ailerons <\/strong>(dont un grand d\u00e9montable).<br><br>\u00c9tant une planche de tr\u00e8s bonne qualit\u00e9 avec un package complet, difficile de dire qu&rsquo;elle n&rsquo;en vaut pas la peine. Si vous recherchez un paddle pour d\u00e9butant robuste avec un magnifique design et tout le n\u00e9cessaire inclus, c&rsquo;est clairement une bonne option.<br><br><strong>Globalement, vous obtenez un paddle avec un bon rapport qualit\u00e9-prix et durable, dont vous profiterez quelques ann\u00e9es. Il vaut sans aucun doute la peine de figurer sur votre liste si vous \u00eates d\u00e9butant et que vous recherchez un paddle.  <\/strong><\/p>\n<\/div><\/div>\n\n\n\n<p>Que pensez-vous du MOAI 10&rsquo;6&Prime; ? Aimez-vous le design tr\u00e8s marqu\u00e9 ou pr\u00e9f\u00e9rez-vous les paddles plus conventionnels sans trop de dessins ?<\/p>\n\n\n\n<p><em>Quel paddle a le meilleur design selon vous et pourquoi ? <\/em><strong>Je sais que le design est avant tout une question de go\u00fbt et je suis curieux de conna\u00eetre vos pr\u00e9f\u00e9rences !<\/strong><\/p>\n\n\n<div class=\"cegg5-container cegg-offers_grid\"><div class=\"container px-0 mb-5 mt-1\" >\n    <div class=\"row g-3 row-cols-2 row-cols-md-3 \">\n        \n                        \n<div class=\"col\">\n    <div class=\"cegg-grid-card card h-100 p-3 \">\n\n        \n        \n        \n                                <div class=\"ratio ratio-1x1 \">\n                <img class=\"card-img-top object-fit-scale rounded\" src=\"https:\/\/moaiboards.com\/wp-content\/uploads\/2021\/10\/sale-10.png\" decoding=\"async\" loading=\"lazy\" alt=\"MOAI SUP 10&#039;6\" title=\"\">            <\/div>\n        \n        <div class=\"card-body p-0 mt-2\">\n                            <div class=\"cegg-merchant small fs-6 text-body-secondary text-truncate\">\n                    <small>Moaiboards.com<\/small>\n                <\/div>\n            \n            \n            \n                <div class=\"cegg-card-price lh-1 pt-3 pb-2\">\n\n                    <div class=\"hstack gap-3\">\n\n                        <div>\n                            <span class=\"cegg-price fs-5 lh-1 mb-0\">\n                                &euro;359.00                            <\/span>\n\n                                                    <\/div>\n\n                        \n                    <\/div>\n\n                    \n                <\/div>\n            \n            \n                            <div class=\"card-title fs-6 fw-normal lh-base cegg-hover-title cegg-text-truncate-2 pt-2\">MOAI SUP 10&#039;6<\/div>            \n            \n            \n        <\/div>\n                    <div class=\"cegg-card-button pt-3\">\n                <div class=\"d-grid\">\n                    <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/moaiboards.com\/fr\/moai-106\/?ref=supworld\" class=\"stretched-link btn btn-outline-primary\">Click for best price<\/a>                <\/div>\n            <\/div>\n        \n    <\/div>\n<\/div>\n            <\/div>\n    \n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator\"\/>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le paddle le plus stable pour d\u00e9buter et un magnifique design Le MOAI 10&rsquo;6&Prime; permet aux d\u00e9butants de se lancer dans le paddle avec beaucoup de stabilit\u00e9 gr\u00e2ce \u00e0 ses 81 cm de large et ses 15 cm d&rsquo;\u00e9paisseur. Il n&rsquo;est pas trop grand pour ne pas \u00eatre trop lent mais assez grand pour offrir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23396,"parent":23220,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"page-templates\/landingpage.php","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[],"tags":[],"class_list":{"0":"post-23373","1":"page","2":"type-page","3":"status-publish","4":"has-post-thumbnail","6":"entry"},"acf":[],"_links":{"self":[{"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/pages\/23373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/comments?post=23373"}],"version-history":[{"count":0,"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/pages\/23373\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/pages\/23220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/media\/23396"}],"wp:attachment":[{"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/media?parent=23373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/categories?post=23373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/standuppaddleboardworld.com\/fr\/wp-json\/wp\/v2\/tags?post=23373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}